{"id":75050,"date":"2022-11-20T18:39:07","date_gmt":"2022-11-20T18:39:07","guid":{"rendered":"https:\/\/tiaclara.com\/?p=75050"},"modified":"2024-03-15T19:26:26","modified_gmt":"2024-03-15T19:26:26","slug":"primeros-auxilios-cocina","status":"publish","type":"post","link":"https:\/\/tiaclara.com\/es\/primeros-auxilios-cocina\/","title":{"rendered":"Primeros Auxilios en la Cocina para Accidentes de Cocina Comunes"},"content":{"rendered":"\n\n\n<p>&iquest;Qu&eacute; hacer si te lastimas cocinando? He aqu&iacute; algunos consejos b&aacute;sicos de primeros auxilios en la cocina para los peque&ntilde;os accidentes comunes en la cocina. Salvo alguna lesi&oacute;n grave, para la que instamos a buscar atenci&oacute;n m&eacute;dica inmediata, estas soluciones b&aacute;sicas son todo lo que necesitar&aacute;s para devolver la diversi&oacute;n a la cocina.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Por <strong><span class=\"entry-author\" itemprop=\"author\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><a href=\"https:\/\/tiaclara.com\/clara-gonzalez\/\" class=\"entry-author-link\" rel=\"author\" itemprop=\"url\"><span class=\"entry-author-name\" itemprop=\"name\">Clara Gonzalez<\/span><\/a><\/span><\/strong> - Revisado <time class=\"entry-modified-time\" itemprop=\"dateModified\" datetime=\"2024-03-15T19:26:26+00:00\">15 Mar 2024<\/time>. Original <meta charset=\"utf-8\">23 Aug 2006.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1813\" height=\"1200\" fetchpriority=\"high\" src=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468.jpg\" alt=\"La llama de la estufa.\" data-skip-lazy class=\"wp-image-75020\" srcset=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468.jpg 1813w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-300x199.jpg 300w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-1024x678.jpg 1024w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-768x508.jpg 768w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-1536x1017.jpg 1536w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-720x477.jpg 720w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-360x238.jpg 360w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468-180x119.jpg 180w\" sizes=\"(max-width: 1813px) 100vw, 1813px\" data-pin-media=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/stove-flame-DSC7468.jpg\"><figcaption class=\"wp-element-caption\">La llama de la estufa.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Botiqu&iacute;n b&aacute;sico de cocina<\/h2>\n\n\n\n<p>Te sugerimos que tengas en casa al menos este <a href=\"https:\/\/amzn.to\/3tLGTxW\" data-eafl-id=\"75031\" data-eafl-parsed=\"1\" class=\"eafl-link eafl-link-text eafl-link-direct\" target=\"_blank\" rel=\"nofollow noreferrer sponsored\">botiqu&iacute;n b&aacute;sico<\/a> (afiliado). Ser&aacute; &uacute;til no s&oacute;lo para los accidentes en la cocina, sino para cualquier accidente dom&eacute;stico. Estos son los productos m&aacute;s b&aacute;sicos que deber&iacute;as tener a mano en casa:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alcohol o toallitas antis&eacute;pticas<\/li>\n\n\n\n<li>Crema antis&eacute;ptica \/ pomada antibi&oacute;tica<\/li>\n\n\n\n<li>Pomada para el tratamiento de quemaduras<\/li>\n\n\n\n<li>Vendaje<\/li>\n\n\n\n<li>Tiritas (banditas)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Accidentes comunes en la cocina<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093.jpg\" alt=\"Picar las patatas.\" class=\"wp-image-74734\" srcset=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093.jpg 1920w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-300x169.jpg 300w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-1024x576.jpg 1024w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-768x432.jpg 768w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-1536x864.jpg 1536w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-480x270.jpg 480w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-720x405.jpg 720w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-360x203.jpg 360w, https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093-180x101.jpg 180w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" data-pin-media=\"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/P1110379.00_00_20_06.Still093.jpg\"><figcaption class=\"wp-element-caption\">Picar las patatas.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Peque&ntilde;os cortadas con cuchillo<\/h3>\n\n\n\n<p><strong>Lo primero que tienes que hacer:<\/strong> Intenta detener el sangrado, y para lograrlo aplica presi&oacute;n sobre el corte.<\/p>\n\n\n\n<p>Una vez que el sangrado haya cesado o disminuido, desinfecta la herida, puedes hacerlo con agua y jab&oacute;n, alcohol o per&oacute;xido. Si tienes alguna en casa, aplica una crema antis&eacute;ptica, algunas marcas contienen sustancias que aceleran el proceso de curaci&oacute;n y reducen las cicatrices. El siguiente paso es aplicar un vendaje para proteger la herida, pero no lo aprietes demasiado; la herida necesita \"respirar\" para curarse.<\/p>\n\n\n\n<p class=\"verde\"><strong>Busca ayuda m&eacute;dica si:<\/strong>&nbsp;La hemorragia no se detiene, el corte va m&aacute;s all&aacute; de la piel o simplemente tiene un aspecto sospechoso. Recuerda tu vacuna antitet&aacute;nica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Peque&ntilde;as quemaduras de cocina<\/h3>\n\n\n\n<p><strong>Lo primero que debes hacer:<\/strong> Pon la parte afectada bajo el chorro de agua fr&iacute;a para bajar la temperatura de la zona afectada y aliviar la sensaci&oacute;n de ardor.<\/p>\n\n\n\n<p>Una vez que el dolor haya disminuido, mant&eacute;n el agua corriendo durante alg&uacute;n tiempo m&aacute;s. Aplica una pomada para tratar las quemaduras. Esto acelerar&aacute; el proceso de curaci&oacute;n y reducir&aacute; las cicatrices. Cubre la quemadura con un vendaje suelto. Nunca pongas mantequilla o margarina sobre una quemadura; esto s&oacute;lo la empeorar&aacute;.<\/p>\n\n\n\n<p>Si una sart&eacute;n se incendia, no la apagues nunca con agua, sofoca las llamas con una tapa herm&eacute;tica o una manta improvisada (puedes utilizar un pa&ntilde;o de cocina).<\/p>\n\n\n\n<p class=\"verde\"><strong>Busca ayuda m&eacute;dica si:<\/strong>&nbsp;M&aacute;s que la capa externa de la piel parece da&ntilde;ada, aparecen ampollas, tiene un aspecto preocupante o sigue doliendo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Envenenamiento<\/h2>\n\n\n\n<p><strong>Lo primero que hay que hacer:<\/strong> Identifica el veneno (siempre que sea posible). <\/p>\n\n\n\n<p>Si el veneno es un producto manufacturado, comprueba si la etiqueta tiene instrucciones para estos casos. Sigue las instrucciones.  <\/p>\n\n\n\n<p>Si la sustancia se ha derramado sobre el cuerpo o los ojos, enjuaga la sustancia con agua corriente.<\/p>\n\n\n\n<p>Tanto si has identificado el veneno como si no,<strong> llama al 911<\/strong> (o al n&uacute;mero de emergencias local) para recibir instrucciones y asistencia. El tiempo es esencial.<\/p>\n\n\n\n<p class=\"verde\"><strong>Busque ayuda m&eacute;dica si:<\/strong> Siempre. Inmediatamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Preguntas frecuentes<\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1668967987693\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Qu&eacute; hacer cuando te cortas en la cocina?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>En caso de cortes leves al cocinar, deten el sangrado aplicando presi&oacute;n, luego limpia la herida con alcohol y aplica una crema antis&eacute;ptica y una tirita. Busca ayuda m&eacute;dica si el sangrado no se detiene.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Gracias a mi marido por revisar esto (est&aacute; formado en primeros auxilios). Esto es s&oacute;lo a t&iacute;tulo informativo; llama a tu n&uacute;mero de emergencia si no est&aacute;s segur@ de lo que debes hacer o busca ayuda de emergencia. M&aacute;s vale prevenir que lamentar.<\/p>\n\n\n\n<p>Para m&aacute;s informaci&oacute;n, visita (en ingl&eacute;s):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.cdc.gov\/SafeChild\/Fact_Sheets\/Burns%20Fact%20Sheet-a.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Hoja informativa de los CDC sobre las quemaduras<\/a> (imprimible)<\/li>\n\n\n\n<li><a href=\"https:\/\/www.redcross.org\/store\/deluxe-family-first-aid-kit\/321275.html?cgid=first-aid-supplies#start=2&amp;cgid=first-aid-supplies\" target=\"_blank\" rel=\"noreferrer noopener\">Sitio web de la Cruz Roja<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hsc.unm.edu\/poison\/_media\/documents\/hsc_eng.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Lista de verificaci&oacute;n para la prevenci&oacute;n de envenenamientos - Universidad de Nuevo M&eacute;xico<\/a> (imprimible)<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group inpost-save\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"save-title\">&iquest;Quieres guardar esta receta?<\/p>\n\n\n\n<p>Entra tu email y te la env&iacute;o por email.&nbsp;<em>&iexcl;Adem&aacute;s recibir&aacute;s fant&aacute;sticas recetas cada semana!<\/em><\/p>\n\n\n<div class=\"fluentform ff-default fluentform_wrapper_5  ff_guten_block ff_guten_block-5 ffs_default_wrap\"><form data-form_id=\"5\" id=\"fluentform_5\" class=\"frm-fluent-form fluent_form_5 ff-el-form-top ff_form_instance_5_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_5_1\" method=\"POST\"><fieldset style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Save Recipe Cocina<\/legend><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&Delta;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"204\"><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><input type=\"hidden\" name=\"__fluent_form_embded_post_id\" value=\"75050\"><input type=\"hidden\" id=\"_fluentform_5_fluentformnonce\" name=\"_fluentform_5_fluentformnonce\" value=\"fcd28ec707\"><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/posts\/75050\"><div data-name=\"ff_cn_id_1\" class=\"ff-t-container ff-column-container ff_columns_total_3 \"><div class=\"ff-t-cell ff-t-column-1\" style=\"flex-basis: 33.33%;\"><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\"><div class=\"ff-t-container\"><div class=\"ff-t-cell \"><div class=\"ff-el-group ff-el-form-hide_label\"><div class=\"ff-el-input--label asterisk-right\"><label for=\"ff_5_names_first_name_\" id=\"label_ff_5_names_first_name_\">First Name<\/label><\/div><div class=\"ff-el-input--content\"><input type=\"text\" name=\"names[first_name]\" id=\"ff_5_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Introduce tu nombre\" aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"ff-t-cell ff-t-column-2\" style=\"flex-basis: 33.33%;\"><div class=\"ff-el-group ff-el-form-hide_label\"><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for=\"ff_5_email_1\" id=\"label_ff_5_email_1\" aria-label=\"Email\">Email<\/label><\/div><div class=\"ff-el-input--content\"><input type=\"email\" name=\"email_1\" id=\"ff_5_email_1\" class=\"ff-el-form-control\" placeholder=\"Email Address *\" data-name=\"email_1\" aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><div class=\"ff-t-cell ff-t-column-3\" style=\"flex-basis: 33.33%;\"><div class=\"ff-el-group ff-text-center ff_submit_btn_wrapper ff_submit_btn_wrapper_custom\"><button class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\" type=\"submit\" name=\"custom_submit_button-5_1\" data-name=\"custom_submit_button-5_1\" aria-label=\"&iexcl;GUARDALA!\">&iexcl;GUARDALA!<\/button><style>form.fluent_form_5 .wpf_has_custom_css.ff-btn-submit { background-color:rgba(58, 109, 21, 1);border-color:rgba(58, 109, 21, 1);color:#FFFFFF;border-radius:0px;min-width:100%; }form.fluent_form_5 .wpf_has_custom_css.ff-btn-submit:hover { background-color:#ffffff;border-color:rgba(58, 109, 21, 1);color:#000000;min-width:100%; } <\/style><\/div><\/div><\/div><\/fieldset><\/form><div id=\"fluentform_5_errors\" class=\"ff-errors-in-stack ff_form_instance_5_1 ff-form-loading_errors ff_form_instance_5_1_errors\"><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_5_1 = {\"id\":\"5\",\"ajaxUrl\":\"https:\\\/\\\/tiaclara.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_5_1\",\"form_id_selector\":\"fluentform_5\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"email_1\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            <\/div><\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Por <strong><strong><span class=\"entry-author\" itemprop=\"author\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><a href=\"https:\/\/tiaclara.com\/clara-gonzalez\/\" class=\"entry-author-link\" rel=\"author\" itemprop=\"url\"><span class=\"entry-author-name\" itemprop=\"name\">Clara Gonzalez<\/span><\/a><\/span><\/strong><\/strong>, publicado 23 Aug 2006 en <a href=\"https:\/\/tiaclara.com\/es\/\">Tia Clara<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 hacer si te lastimas cocinando? He aqu\u00ed algunos consejos b\u00e1sicos de primeros auxilios en la cocina para los peque\u00f1os accidentes comunes en la cocina. Salvo alguna lesi\u00f3n grave, para la que instamos a buscar atenci\u00f3n m\u00e9dica inmediata, estas soluciones b\u00e1sicas son todo lo que necesitar\u00e1s para devolver la diversi\u00f3n a la cocina.<\/p>\n","protected":false},"author":201623,"featured_media":75027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","grocers_list_post_gated":"","grocers_list_recipe_card_gated":"","grocers_list_no_gating":"","footnotes":""},"categories":[3161],"cultivate_rss":[],"class_list":{"0":"post-75050","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-como-hacer","8":"entry"},"acf":[],"featured_image_src":"https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468.jpg","author_info":{"display_name":"Clara Gonzalez","author_link":"https:\/\/tiaclara.com\/es\/author\/tiaclara\/"},"uagb_featured_image_src":{"full":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468.jpg",1200,1200,false],"thumbnail":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-150x150.jpg",150,150,true],"medium":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-300x300.jpg",300,300,true],"medium_large":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-768x768.jpg",720,720,true],"large":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-1024x1024.jpg",720,720,true],"1536x1536":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468.jpg",1200,1200,false],"2048x2048":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468.jpg",1200,1200,false],"wprm-metadata-1_1":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-500x500.jpg",500,500,true],"wprm-metadata-4_3":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-500x375.jpg",500,375,true],"wprm-metadata-16_9":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-480x270.jpg",480,270,true],"feast-square-1x1-720x720":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-720x720.jpg",720,720,true],"feast-square-1x1-360x360":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-360x360.jpg",360,360,true],"feast-square-1x1-180x180":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-180x180.jpg",180,180,true],"feast-content-720px-wide":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-720x720.jpg",720,720,true],"feast-content-360px-wide":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-360x360.jpg",360,360,true],"feast-content-180px-wide":["https:\/\/tiaclara.com\/wp-content\/uploads\/2022\/11\/kitchen-first-aid-DSC7468-180x180.jpg",180,180,true]},"uagb_author_info":{"display_name":"Clara Gonzalez","author_link":"https:\/\/tiaclara.com\/es\/author\/tiaclara\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfQu\u00e9 hacer si te lastimas cocinando? He aqu\u00ed algunos consejos b\u00e1sicos de primeros auxilios en la cocina para los peque\u00f1os accidentes comunes en la cocina. Salvo alguna lesi\u00f3n grave, para la que instamos a buscar atenci\u00f3n m\u00e9dica inmediata, estas soluciones b\u00e1sicas son todo lo que necesitar\u00e1s para devolver la diversi\u00f3n a la cocina.","_links":{"self":[{"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/posts\/75050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/users\/201623"}],"replies":[{"embeddable":true,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/comments?post=75050"}],"version-history":[{"count":10,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/posts\/75050\/revisions"}],"predecessor-version":[{"id":106463,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/posts\/75050\/revisions\/106463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/media\/75027"}],"wp:attachment":[{"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/media?parent=75050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/categories?post=75050"},{"taxonomy":"cultivate_rss","embeddable":true,"href":"https:\/\/tiaclara.com\/es\/wp-json\/wp\/v2\/cultivate_rss?post=75050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}